{"id":12705,"date":"2025-10-21T16:47:30","date_gmt":"2025-10-21T16:47:30","guid":{"rendered":"https:\/\/laurahome.pt\/produto\/jogo-de-cama-flanela-risca-cinza\/"},"modified":"2026-07-04T15:12:00","modified_gmt":"2026-07-04T15:12:00","slug":"jogo-de-cama-flanela-risca-cinza","status":"publish","type":"product","link":"https:\/\/laurahome.pt\/es\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/","title":{"rendered":"Juego de Cama Franela Raya Gris"},"content":{"rendered":"<h2 style=\"text-align:justify;\">La suavidad de la franela de algod\u00f3n portugu\u00e9s<\/h2>\n<p style=\"text-align:justify;\">A\u00f1ada un toque de sofisticaci\u00f3n y comodidad a su dormitorio con las S\u00e1banas de Cama Franela Raya Gris. Esta es una creaci\u00f3n de excelencia fabricada en Portugal, en honor a la tradici\u00f3n textil que se siente en Valen\u00e7a do Minho. Producidas en franela 100% Algod\u00f3n, la fibra est\u00e1 cardada por ambos lados para garantizar una textura suave y un aislamiento t\u00e9rmico ideal para el invierno.<\/p>\n<h2 style=\"text-align:justify;\">Durabilidad y tratamiento sanforizado<\/h2>\n<p style=\"text-align:justify;\">Estas s\u00e1banas t\u00e9rmicas para el fr\u00edo pasan por un tratamiento sanforizado, lo que evita el encogimiento y garantiza que la pieza mantenga su aspecto impecable y tacto suave tras varios lavados. El patr\u00f3n de rayas delicadas en la s\u00e1bana encimera combina elegancia moderna con el confort tradicional de la franela, adapt\u00e1ndose a cualquier estilo de decoraci\u00f3n.<\/p>\n<h2 style=\"text-align:justify;\">Ventajas y beneficios del producto<\/h2>\n<ul>\n<li><strong>Franela 100% Algod\u00f3n:<\/strong> Tacto suave, c\u00e1lido y altamente transpirable, ideal para pieles sensibles.<\/li>\n<li><strong>Alta durabilidad:<\/strong> Mantiene el confort y la estructura textil incluso con un uso intensivo.<\/li>\n<li><strong>Dise\u00f1o vers\u00e1til:<\/strong> Patr\u00f3n de rayas grises que realza la est\u00e9tica del dormitorio.<\/li>\n<\/ul>\n<h2 style=\"text-align:justify;\">Cuidados de mantenimiento<\/h2>\n<p style=\"text-align:justify;\">Para preservar la calidad superior de este conjunto, recomendamos:<\/p>\n<ul>\n<li>Lavar antes del primer uso sin suavizante.<\/li>\n<li>Lavar a m\u00e1quina a 40\u00b0C como m\u00e1ximo con centrifugado corto.<\/li>\n<li>No usar lej\u00eda ni blanqueador.<\/li>\n<li>Planchar m\u00e1ximo 150\u00b0C.<\/li>\n<li>Se puede usar la secadora a temperatura reducida.<\/li>\n<\/ul>\n<h2 style=\"text-align:justify;\">Gu\u00eda de tallas disponibles<\/h2>\n<p style=\"text-align:justify;\">Disponemos de varias medidas para ajustarse perfectamente a su colch\u00f3n (incluye s\u00e1bana encimera, s\u00e1bana bajera ajustable y fundas de almohada):<\/p>\n<p><strong>Cama de 90 x 200 cm<\/strong><br \/> &#8211; S\u00e1bana encimera de 160 x 290 cm;<br \/> \u2013 S\u00e1bana Bajera Ajustable de 90 x 200 + 30 cm;<br \/> &#8211; Travesa\u00f1o de 45 x 115 cm.<\/p>\n<p><strong>Cama de 105 x 200 cm<\/strong><br \/> \u2013 S\u00e1bana encimera de 180 x 290 cm;<br \/> \u2013 S\u00e1bana Bajera Ajustable de 105 x 200 cm;<br \/> &#8211; Travesa\u00f1o de 45 x 120 cm.<\/p>\n<p><strong>Cama de 140 x 200 cm<\/strong><br \/> &#8211; S\u00e1bana encimera de 210 x 290 cm;<br \/> \u2013 S\u00e1bana Bajera Ajustable de 140 x 200 cm;<br \/> &#8211; Elija entre: 1 Travesa\u00f1o de 45 x 155 cm O 2 Almohadas de 50 x 70 cm.<\/p>\n<p><strong>Cama de 150 x 200 cm<\/strong><br \/> &#8211; S\u00e1bana encimera de 230 x 290 cm;<br \/> \u2013 S\u00e1bana Bajera Ajustable de 150 x 200 cm;<br \/> &#8211; Travesa\u00f1o de 45 x 165 cm.<\/p>\n<p><strong>Cama de 160 x 200 cm<\/strong><br \/> &#8211; S\u00e1bana encimera de 240 x 290 cm;<br \/> \u2013 S\u00e1bana Bajera Ajustable de 160 x 200 cm;<br \/> \u2013 2 Fundas de almohada de 50 x 80 cm.<\/p>\n<p><strong>Cama de 180 x 200 cm<\/strong><br \/> &#8211; S\u00e1bana encimera de 260 x 290 cm;<br \/> \u2013 S\u00e1bana Bajera Ajustable de 180 x 200 cm;<br \/> &#8211; 2 Almohadas de 50 x 90 cm.<\/p>\n<p><strong>Cama de 200 x 200 cm<\/strong><br \/> &#8211; S\u00e1bana encimera de 280 x 290 cm;<br \/> \u2013 S\u00e1bana Bajera Ajustable de 200 x 200 cm;<br \/> &#8211; 2 Almohadas de 50 x 100 cm.<\/p>\n<h2 style=\"text-align:justify;\">Cuidados de mantenimiento<\/h2>\n<ul>\n<li>Lavar antes del primer uso sin suavizante.<\/li>\n<li>Lavar a m\u00e1quina a 40\u00b0C como m\u00e1ximo &#8211; centrifugado corto.<\/li>\n<li>No utilizar lej\u00eda\/blanqueador.<\/li>\n<li>Planchar a un m\u00e1ximo de 150\u00b0C.<\/li>\n<li>No limpiar en seco.<\/li>\n<li>Se puede usar la secadora a temperatura reducida.<\/li>\n<\/ul>\n<p><em>Nota: los colores pueden variar ligeramente debido a la configuraci\u00f3n del monitor.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<h2 style=\"text-align:justify;\">Juego de cama t\u00e9rmico con la calidad de Valen\u00e7a<\/h2>\n<p style=\"text-align:justify;\">Sienta el confort \u00fanico de la franela 100% Algod\u00f3n en este juego de cama de rayas grises. Con el sello de excelencia y tradici\u00f3n que encuentra en Valen\u00e7a do Minho, este conjunto une la suavidad extrema al dise\u00f1o moderno para las noches m\u00e1s fr\u00edas.<\/p>","protected":false},"featured_media":12703,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2579,2593,2570],"product_tag":[],"class_list":["post-12705","product","type-product","status-publish","has-post-thumbnail","product_cat-lencois","product_cat-conjunto-de-lencois-de-flanela","product_cat-quarto","pa_composicao-100algodao","pa_cor-cinzento","pa_fabricadoem-portugal","pa_medidadelencois-105x200cmtravesseiro45x120cm","pa_medidadelencois-140x200cm2fronhas50x70cm","pa_medidadelencois-140x200cmtravesseiro45x155cm","pa_medidadelencois-150160x200cm2fronhas50x80cm","pa_medidadelencois-150x200cmtravesseiro45x170cm","pa_medidadelencois-180x200cm2fronhas50x90cm","pa_medidadelencois-200x200cm2fronhas50x100cm","pa_medidadelencois-90x200cmtravesseiro45x110cm","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jogo de Cama Flanela Risca Cinza 100% Algod\u00e3o | Laura Home<\/title>\n<meta name=\"description\" content=\"Descubra o conforto dos len\u00e7\u00f3is de flanela de algod\u00e3o com a qualidade de Valen\u00e7a. Design de riscas cinza, toque macio e t\u00e9rmico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laurahome.pt\/es\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jogo de Cama Flanela Risca Cinza 100% Algod\u00e3o | Laura Home\" \/>\n<meta property=\"og:description\" content=\"Descubra o conforto dos len\u00e7\u00f3is de flanela de algod\u00e3o com a qualidade de Valen\u00e7a. Design de riscas cinza, toque macio e t\u00e9rmico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laurahome.pt\/es\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/\" \/>\n<meta property=\"og:site_name\" content=\"Laura Home Online Valen\u00e7a\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-04T15:12:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laurahome.pt\/wp-content\/uploads\/2025\/10\/2469-Jogo-de-Cama-Flanela-Risca-Cinza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laurahome.pt\\\/loja\\\/quarto\\\/lencois\\\/conjunto-de-lencois-de-flanela\\\/jogo-de-cama-flanela-risca-cinza\\\/\",\"url\":\"https:\\\/\\\/laurahome.pt\\\/loja\\\/quarto\\\/lencois\\\/conjunto-de-lencois-de-flanela\\\/jogo-de-cama-flanela-risca-cinza\\\/\",\"name\":\"Jogo de Cama Flanela Risca Cinza 100% Algod\u00e3o | Laura Home\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laurahome.pt\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laurahome.pt\\\/loja\\\/quarto\\\/lencois\\\/conjunto-de-lencois-de-flanela\\\/jogo-de-cama-flanela-risca-cinza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/laurahome.pt\\\/loja\\\/quarto\\\/lencois\\\/conjunto-de-lencois-de-flanela\\\/jogo-de-cama-flanela-risca-cinza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laurahome.pt\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/2469-Jogo-de-Cama-Flanela-Risca-Cinza.jpg\",\"datePublished\":\"2025-10-21T16:47:30+00:00\",\"dateModified\":\"2026-07-04T15:12:00+00:00\",\"description\":\"Descubra o conforto dos len\u00e7\u00f3is de flanela de algod\u00e3o com a qualidade de Valen\u00e7a. Design de riscas cinza, toque macio e t\u00e9rmico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laurahome.pt\\\/loja\\\/quarto\\\/lencois\\\/conjunto-de-lencois-de-flanela\\\/jogo-de-cama-flanela-risca-cinza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laurahome.pt\\\/loja\\\/quarto\\\/lencois\\\/conjunto-de-lencois-de-flanela\\\/jogo-de-cama-flanela-risca-cinza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/laurahome.pt\\\/loja\\\/quarto\\\/lencois\\\/conjunto-de-lencois-de-flanela\\\/jogo-de-cama-flanela-risca-cinza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/laurahome.pt\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/2469-Jogo-de-Cama-Flanela-Risca-Cinza.jpg\",\"contentUrl\":\"https:\\\/\\\/laurahome.pt\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/2469-Jogo-de-Cama-Flanela-Risca-Cinza.jpg\",\"width\":2000,\"height\":2000,\"caption\":\"Jogo de Cama Flanela Risca Cinza\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laurahome.pt\\\/loja\\\/quarto\\\/lencois\\\/conjunto-de-lencois-de-flanela\\\/jogo-de-cama-flanela-risca-cinza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/laurahome.pt\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/laurahome.pt\\\/es\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jogo de Cama Flanela Risca Cinza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laurahome.pt\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/laurahome.pt\\\/es\\\/\",\"name\":\"LAURA HOME | VALEN\u00c7A\",\"description\":\"Loja Online de Laura Home em Valen\u00e7a do Minho. Os melhores produtos t\u00eaxteis est\u00e3o aqui.\",\"publisher\":{\"@id\":\"https:\\\/\\\/laurahome.pt\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laurahome.pt\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laurahome.pt\\\/es\\\/#organization\",\"name\":\"LAURA HOME | VALEN\u00c7A\",\"url\":\"https:\\\/\\\/laurahome.pt\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/laurahome.pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/laurahome.pt\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo-laura-home-.png\",\"contentUrl\":\"https:\\\/\\\/laurahome.pt\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logo-laura-home-.png\",\"width\":601,\"height\":537,\"caption\":\"LAURA HOME | VALEN\u00c7A\"},\"image\":{\"@id\":\"https:\\\/\\\/laurahome.pt\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jogo de Cama Flanela Risca Cinza 100% Algod\u00e3o | Laura Home","description":"Descubra o conforto dos len\u00e7\u00f3is de flanela de algod\u00e3o com a qualidade de Valen\u00e7a. Design de riscas cinza, toque macio e t\u00e9rmico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laurahome.pt\/es\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/","og_locale":"es_ES","og_type":"article","og_title":"Jogo de Cama Flanela Risca Cinza 100% Algod\u00e3o | Laura Home","og_description":"Descubra o conforto dos len\u00e7\u00f3is de flanela de algod\u00e3o com a qualidade de Valen\u00e7a. Design de riscas cinza, toque macio e t\u00e9rmico.","og_url":"https:\/\/laurahome.pt\/es\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/","og_site_name":"Laura Home Online Valen\u00e7a","article_modified_time":"2026-07-04T15:12:00+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/laurahome.pt\/wp-content\/uploads\/2025\/10\/2469-Jogo-de-Cama-Flanela-Risca-Cinza.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/laurahome.pt\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/","url":"https:\/\/laurahome.pt\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/","name":"Jogo de Cama Flanela Risca Cinza 100% Algod\u00e3o | Laura Home","isPartOf":{"@id":"https:\/\/laurahome.pt\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/laurahome.pt\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/#primaryimage"},"image":{"@id":"https:\/\/laurahome.pt\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/#primaryimage"},"thumbnailUrl":"https:\/\/laurahome.pt\/wp-content\/uploads\/2025\/10\/2469-Jogo-de-Cama-Flanela-Risca-Cinza.jpg","datePublished":"2025-10-21T16:47:30+00:00","dateModified":"2026-07-04T15:12:00+00:00","description":"Descubra o conforto dos len\u00e7\u00f3is de flanela de algod\u00e3o com a qualidade de Valen\u00e7a. Design de riscas cinza, toque macio e t\u00e9rmico.","breadcrumb":{"@id":"https:\/\/laurahome.pt\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laurahome.pt\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/laurahome.pt\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/#primaryimage","url":"https:\/\/laurahome.pt\/wp-content\/uploads\/2025\/10\/2469-Jogo-de-Cama-Flanela-Risca-Cinza.jpg","contentUrl":"https:\/\/laurahome.pt\/wp-content\/uploads\/2025\/10\/2469-Jogo-de-Cama-Flanela-Risca-Cinza.jpg","width":2000,"height":2000,"caption":"Jogo de Cama Flanela Risca Cinza"},{"@type":"BreadcrumbList","@id":"https:\/\/laurahome.pt\/loja\/quarto\/lencois\/conjunto-de-lencois-de-flanela\/jogo-de-cama-flanela-risca-cinza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/laurahome.pt\/es\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/laurahome.pt\/es\/loja\/"},{"@type":"ListItem","position":3,"name":"Jogo de Cama Flanela Risca Cinza"}]},{"@type":"WebSite","@id":"https:\/\/laurahome.pt\/es\/#website","url":"https:\/\/laurahome.pt\/es\/","name":"LAURA HOME | VALEN\u00c7A","description":"Loja Online de Laura Home em Valen\u00e7a do Minho. Os melhores produtos t\u00eaxteis est\u00e3o aqui.","publisher":{"@id":"https:\/\/laurahome.pt\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laurahome.pt\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/laurahome.pt\/es\/#organization","name":"LAURA HOME | VALEN\u00c7A","url":"https:\/\/laurahome.pt\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/laurahome.pt\/es\/#\/schema\/logo\/image\/","url":"https:\/\/laurahome.pt\/wp-content\/uploads\/2026\/06\/logo-laura-home-.png","contentUrl":"https:\/\/laurahome.pt\/wp-content\/uploads\/2026\/06\/logo-laura-home-.png","width":601,"height":537,"caption":"LAURA HOME | VALEN\u00c7A"},"image":{"@id":"https:\/\/laurahome.pt\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/laurahome.pt\/es\/wp-json\/wp\/v2\/product\/12705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurahome.pt\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/laurahome.pt\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/laurahome.pt\/es\/wp-json\/wp\/v2\/comments?post=12705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurahome.pt\/es\/wp-json\/wp\/v2\/media\/12703"}],"wp:attachment":[{"href":"https:\/\/laurahome.pt\/es\/wp-json\/wp\/v2\/media?parent=12705"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/laurahome.pt\/es\/wp-json\/wp\/v2\/product_brand?post=12705"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/laurahome.pt\/es\/wp-json\/wp\/v2\/product_cat?post=12705"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/laurahome.pt\/es\/wp-json\/wp\/v2\/product_tag?post=12705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}